{"id":10306,"date":"2023-03-14T11:07:01","date_gmt":"2023-03-14T11:07:01","guid":{"rendered":"https:\/\/impacte.com\/?p=10306"},"modified":"2025-04-07T15:05:10","modified_gmt":"2025-04-07T15:05:10","slug":"5-funciones-o-trucos-utiles-para-word","status":"publish","type":"post","link":"https:\/\/impacte.com\/es\/5-funciones-o-trucos-utiles-para-word\/","title":{"rendered":"5 funciones o trucos \u00fatiles para Word"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb50%\u00bb max_width=\u00bb50%\u00bb module_alignment=\u00bbcenter\u00bb animation_style=\u00bbzoom\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb min_height=\u00bb163.2px\u00bb custom_padding=\u00bb||2px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb min_height=\u00bb139.8px\u00bb custom_padding=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p style=\"text-align: justify;\"><strong><\/strong><\/p>\n<p><strong><\/strong><\/p>\n<h5 style=\"text-align: justify;\">En este blog nos encanta automatizar tareas. Si para hacer una cosa nos hacen falta dos clics, siempre intentaremos encontrar la manera de hacerlo con uno solo. Hoy te ense\u00f1amos 5 funciones o trucos \u00fatiles para Word para ahorrar un poco de tiempo, trabajar mejor o modificar el estilo de tus documentos. Como siempre puedes mirar el tutorial paso a paso en video o leerlo en modo texto. Esperamos te sean de utilidad.<\/h5>\n<h4><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.20.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_video src=\u00bbhttps:\/\/youtu.be\/8oWLDLxICnU\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb min_height=\u00bb103.2px\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<h3><strong>1. Generar texto aleatorio autom\u00e1ticamente:<\/strong><\/h3>\n<p><strong><\/strong><\/p>\n<p style=\"text-align: justify;\">Si necesitas a\u00f1adir un texto largo, varias frases y\/o varios p\u00e1rrafos, pero te da igual qu\u00e9 texto sea, tenemos la funci\u00f3n adecuada para hacerlo en 3 segundos. Simplemente tienes que escribir, all\u00ed donde quieras que aparezca el texto, lo siguiente: =rand(X,Y) donde X es el n\u00famero de p\u00e1rrafos e Y es el n\u00famero de frases. Para un texto de 3 p\u00e1rrafos de 5 frases cada uno, escribe: =rand(3,5) Inmediatamente despu\u00e9s de cerrar el par\u00e9ntesis presiona \u00abintro\u00bb y un texto aleatorio del tama\u00f1o que hayas definido se generar\u00e1 autom\u00e1ticamente. Es importante que el intro lo hagas justo despu\u00e9s de cerrar el par\u00e9ntesis, ya que si introduces cualquier car\u00e1cter, aunque sea un espacio, antes de pulsar intro, Word lo interpretar\u00e1 como un texto cualquiera y no generar\u00e1 el texto aleatorio.<\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 22px; text-align: left;\"><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 22px; text-align: left;\"><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 22px; text-align: left;\">2. Ver dos p\u00e1ginas a la vez<\/strong><\/p>\n<h3> <\/h3>\n<p style=\"text-align: justify;\">Si tenemos un documento con varias p\u00e1ginas, y tenemos que trabajar con dos de ellas que se encuentran alejadas (la p\u00e1gina 2 y la p\u00e1gina 14, por ejemplo), perderemos bastante tiempo en movernos de una a otra. Y cuantas m\u00e1s veces nos tengamos que mover, m\u00e1s tiempo perderemos. \u00bfQue bien que nos ir\u00eda poder ver las dos p\u00e1ginas a la vez en la misma pantalla, verdad? Pues es muy f\u00e1cil, simplemente tienes que apretar a la vez las siguientes teclas: Control + Alt + V. La pantalla de trabajo ha quedado dividida en dos mitades, pudiendo trabajar en una mitad con una p\u00e1gina del documento, y con otra p\u00e1gina en la otra mitad, como puedes ver en la siguiente imagen:<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_image src=\u00bbhttps:\/\/impacte.com\/wp-content\/uploads\/2023\/03\/figura1.png\u00bb alt=\u00bb5 funciones o trucos utiles para word. Como ver dos p\u00e1ginas a la vez en Microsoft Word\u00bb title_text=\u00bbfigura1&#8243; align=\u00bbcenter\u00bb _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Para quitar esta vista y volver a la vista normal de una p\u00e1gina, debes teclear: Alt + May\u00fasculas + C<\/p>\n<p><strong style=\"font-size: 22px;\"><\/strong><\/p>\n<p><strong style=\"font-size: 22px;\">3. A\u00f1adir una marca de agua<\/strong><\/p>\n<p><strong style=\"font-size: 22px;\"><\/strong><\/p>\n<p style=\"text-align: justify;\">Para a\u00f1adir una marca de agua al documento a modo de sello, deberemos ir a la pesta\u00f1a \u00abDise\u00f1o\u00bb de la cinta de opciones y hacer clic en \u00abMarca de agua\u00bb. Podemos elegir cualquiera de las opciones predefinidas que incorpora Word o crear una personalizada, que podr\u00e1 ser con una imagen o con un texto. Si escogemos una imagen, podremos ajustar el tama\u00f1o (hacerla m\u00e1s grande o m\u00e1s peque\u00f1a) y decolorarla. Si seleccionamos un texto, podremos escoger qu\u00e9 texto saldr\u00e1, el tama\u00f1o y tipolog\u00eda de letra, el color, si la queremos semi-transparente o no y si se tiene que ver en horizontal o diagonal. En la siguiente imagen vemos una marca de agua de texto personalizado, con el texto \u00abIMPACTE\u00bb de color rojo, semi-transparente y en diagonal:<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_image src=\u00bbhttps:\/\/impacte.com\/wp-content\/uploads\/2023\/03\/figura2.png\u00bb alt=\u00bbCom a\u00f1adir una marca de agua a un documento de word\u00bb title_text=\u00bbfigura2&#8243; _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.20.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<h3><strong>4. Darle formato a palabras separadas a la vez<\/strong><\/h3>\n<p><strong><\/strong><\/p>\n<p style=\"text-align: justify;\">Mucha gente domina eso, pero si eres de los que todav\u00eda no lo sabe, vas a descubrir un mundo nuevo. Si tienes que cambiar el formato de varias palabras que no se encuentran juntas, seleccionarlas con el rat\u00f3n de la manera habitual no te servir\u00e1, ya que se seleccionan todas las palabras seguidas. Pero si presionas la tecla \u00abControl\u00bb y mientras la mantenes presionada seleccionas palabras separadas ver\u00e1s que seleccionar\u00e1 s\u00f3lo aquellas palabras que elijas con el rat\u00f3n. De esta forma podr\u00e1s cambiarle el formato a todas a la vez en lugar de ir una por una.<\/p>\n<p><strong style=\"font-size: 22px;\"><\/strong><\/p>\n<p><strong style=\"font-size: 22px;\">5. Abrir directamente un nuevo documento cuando se inicia Word<\/strong><\/p>\n<p><strong style=\"font-size: 22px;\"><\/strong><\/p>\n<p style=\"text-align: justify;\">Si abres el Word directamente por el cceso directo del programa (en lugar de abrirlo haciendo doble clic en un documento que tengas guardado), ver\u00e1s la p\u00e1gina de inicio de Word. Desde esta p\u00e1gina puedes abrir una plantilla, uno de los documentos m\u00e1s recientes, cualquier documento almacenado en tu ordenador o en la nube, o un documento en blanco. Si la mayor\u00eda de veces abres un documento en blanco, te puedes ahorrar un clic configurando Word para que abra directamente un documento en blanco cuando se abra a aplicaci\u00f3n. Para ello, debemos ir a las opciones de Word (Men\u00fa Archivo, Opciones) y all\u00ed, en la pesta\u00f1a \u00abGeneral\u00bb bajar hasta donde dice \u00abOpciones de inicio\u00bb. En ella encontraremos una casilla marcada que dice \u00abMostrar la pantalla de inicio cuando se inicie esta aplicaci\u00f3n\u00bb. Desm\u00e1rcala y la pr\u00f3xima vez que abras el Word, \u00e9ste abrir\u00e1 directamente un documento en blanco.<\/p>\n<p>&nbsp;<\/p>\n<p>Esperamos que estos trucos te sirvan de ayuda. Puedes visitar nuestro <a href=\"https:\/\/impacte.com\/es\/blog\/\">blog<\/a> para m\u00e1s tutoriales, tanto de <a href=\"https:\/\/ca.wikipedia.org\/wiki\/Microsoft_Word\" target=\"_blank\" rel=\"noopener\">Word<\/a> omo de otras aplicaciones. \u00a1Salud y automatizaci\u00f3n!<\/p>\n<p style=\"text-align: justify;\">\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb animation_style=\u00bbfold\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_divider _builder_version=\u00bb4.16&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb50%\u00bb max_width=\u00bb50%\u00bb module_alignment=\u00bbcenter\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este blog nos encanta automatizar tareas. Si para hacer una cosa nos hacen falta dos clics, siempre intentaremos encontrar la manera de hacerlo con uno solo. Hoy te ense\u00f1amos 5 funciones o trucos \u00fatiles para Word para ahorrar un poco de tiempo, trabajar mejor o modificar el estilo de tus documentos. Como siempre puedes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":987515546,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"1080","footnotes":""},"categories":[28,37],"tags":[90,62,91,50,89],"class_list":["post-10306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tutoriales-es","category-microsoft-word","tag-funciones","tag-paso-a-paso","tag-trucos","tag-tutorial","tag-word"],"_links":{"self":[{"href":"https:\/\/impacte.com\/es\/wp-json\/wp\/v2\/posts\/10306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/impacte.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/impacte.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/impacte.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/impacte.com\/es\/wp-json\/wp\/v2\/comments?post=10306"}],"version-history":[{"count":3,"href":"https:\/\/impacte.com\/es\/wp-json\/wp\/v2\/posts\/10306\/revisions"}],"predecessor-version":[{"id":987515666,"href":"https:\/\/impacte.com\/es\/wp-json\/wp\/v2\/posts\/10306\/revisions\/987515666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/impacte.com\/es\/wp-json\/wp\/v2\/media\/987515546"}],"wp:attachment":[{"href":"https:\/\/impacte.com\/es\/wp-json\/wp\/v2\/media?parent=10306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/impacte.com\/es\/wp-json\/wp\/v2\/categories?post=10306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/impacte.com\/es\/wp-json\/wp\/v2\/tags?post=10306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}